{"id":15038,"date":"2020-03-25T15:44:59","date_gmt":"2020-03-25T14:44:59","guid":{"rendered":"https:\/\/www.andaluciarural.eu\/?page_id=15038"},"modified":"2020-07-13T15:43:36","modified_gmt":"2020-07-13T13:43:36","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/","title":{"rendered":"T\u00e9rminos y condiciones"},"content":{"rendered":"<h5><strong>Condiciones de viaje<\/strong><\/h5>\n<p>Andalucia Rural (en lo sucesivo denominado AR) La Cueva (La Estrella &amp; El Sol), El Garzopo, La Rueda<\/p>\n<p>Los Agustines, Tijola 84, E-18400 Orgiva, Granada, Espa\u00f1a<\/p>\n<p>Homepage: www.andaluciarural.eu<br \/>\nContacto: info@andaluciarural.eu<\/p>\n<h5><strong>Reserva, confirmaci\u00f3n de viaje<\/strong><\/h5>\n<p>La reserva se puede hacer por escrito o por Internet en AR. Al realizar la reserva, le ofrece a AR la conclusi\u00f3n del contrato de viaje final, su reserva ser\u00e1 vinculante hasta la confirmaci\u00f3n por escrito de AR. El contrato de viaje se concluye mediante una confirmaci\u00f3n de viaje por escrito (por Internet a trav\u00e9s de correo electr\u00f3nico) por parte de AR, que se produce de inmediato. Se reserva la correcci\u00f3n de errores obvios, por ejemplo, debido a errores de impresi\u00f3n o c\u00e1lculo o errores de asignaci\u00f3n en Internet.<br \/>\nLas solicitudes especiales solo son v\u00e1lidas si AR las confirma por escrito.<\/p>\n<h5><strong>Pagos, documentos de viaje<\/strong><\/h5>\n<p>El dep\u00f3sito es del 20% del precio del viaje. La confirmaci\u00f3n de viaje es su documento de viaje y simult\u00e1neamente la aceptaci\u00f3n vinculante de la oferta de contrato de viaje de AR que ofrece. El saldo restante se pagar\u00e1 de acuerdo con las instrucciones en la confirmaci\u00f3n, en todo caso, a m\u00e1s tardar en efectivo una vez que est\u00e9 aqu\u00ed.<\/p>\n<h5><strong>Cargos por servicio extra local<\/strong><\/h5>\n<p>Todos est\u00e1n enumerados en la confirmaci\u00f3n del viaje. Cargos adicionales como, por ejemplo, cena o desayuno en La Rueda, u otros cargos adicionales, como por ejemplo. Las mermeladas caseras, nuestro propio aceite de oliva, postales, le\u00f1a, etc. se facturar\u00e1n localmente seg\u00fan el uso.<\/p>\n<h5><strong>Limpieza<\/strong><\/h5>\n<p>Los alquileres se limpiar\u00e1n por completo antes de su llegada e incluir\u00e1n todas las s\u00e1banas, toallas y pa\u00f1os de cocina, con la excepci\u00f3n de las toallas de playa \/ piscina, que le pedimos que traiga. Le daremos un cambio de s\u00e1banas y toallas cada 7 d\u00edas, sin ning\u00fan cargo adicional. No hay ning\u00fan cargo adicional por la limpieza cuando salga, pero s\u00ed esperamos que nuestros hu\u00e9spedes salgan de las casas en condiciones ordenadas y previamente limpias.<\/p>\n<h5><strong>Camas extra<\/strong><\/h5>\n<p>Se puede proporcionar a pedido. Los alquileres, sin embargo, tienen un n\u00famero de ocupaci\u00f3n m\u00e1xima. El precio b\u00e1sico del alquiler es para la ocupaci\u00f3n de 2 personas; por cada hu\u00e9sped adicional se aplica una tarifa adicional por noche, como se indica en el anuncio. La propiedad de alquiler no puede ser ocupada por m\u00e1s personas que la ocupaci\u00f3n m\u00e1xima establecida. El n\u00famero m\u00e1ximo especificado tambi\u00e9n incluye hijos. Si hay m\u00e1s hu\u00e9spedes utilizando la casa, de lo acordado en el contrato, AR tiene derecho a pedirle que se vaya de inmediato, sin ning\u00fan derecho de reembolso.<\/p>\n<h5><strong>Mascotas<\/strong><\/h5>\n<p>Se permiten en principio (excepto en El Garzopo), cuando se mencionan al momento de la reserva. No hay costos adicionales. Sin embargo, se espera que su (s) mascota (s) se porten bien y no causen ning\u00fan da\u00f1o, de lo contrario tendremos que cobrar por ello.<\/p>\n<h5><strong>Equipo<\/strong><\/h5>\n<p>En todos los alquileres se proporcionan vajilla y cuberter\u00eda suficientes para el n\u00famero de hu\u00e9spedes reservados. Se proporciona un refrigerador en cada casa como equipo b\u00e1sico y, por lo tanto, no se menciona expl\u00edcitamente en la descripci\u00f3n del art\u00edculo. Todos los dem\u00e1s artefactos t\u00e9cnicos, como horno, microondas, lavavajillas, cafetera, solo est\u00e1n disponibles cuando se mencionan expl\u00edcitamente en la descripci\u00f3n. En el anuncio mencionamos muebles de jard\u00edn, aunque no es obligatorio que haya una silla de jard\u00edn \/ tumbona disponible para cada persona.<\/p>\n<h5><strong>Dep\u00f3sito y cuidado<\/strong><\/h5>\n<p>Al alquilar cualquier de nuestras casas, tendr\u00e1 derecho a utilizar dicha propiedad, incluidos muebles y utensilios. Usted acepta tratar la propiedad y su inventario y las instalaciones de la comunidad con el m\u00e1ximo cuidado. Se le requiere que reemplace cualquier da\u00f1o durante el per\u00edodo de alquiler causado por su culpa o la culpa de sus compa\u00f1eros o invitados. AR tiene derecho a exigir un dep\u00f3sito razonable. El dep\u00f3sito se depositar\u00e1 en efectivo. El dep\u00f3sito ser\u00e1 devuelto a la devoluci\u00f3n adecuada de la propiedad alquilada en efectivo.<\/p>\n<h5><strong>Llegada e ida<\/strong><\/h5>\n<p>El horario de llegada es variable y depende de la solicitud de los hu\u00e9spedes, pero debe acordarse de antemano. AR asegura la recepci\u00f3n y la recogida de llaves. A la salida, de acuerdo con la confirmaci\u00f3n de la reserva, los alquileres deben dejarse a m\u00e1s tardar a las 11:00 a menos que se indique lo contrario.<\/p>\n<h5><strong>Servicios<\/strong><\/h5>\n<p>Para el alcance y el tipo de servicios que proporcionar\u00e1 AR en el marco del contrato de viaje, solo son v\u00e1lidas las descripciones, ilustraciones e informaci\u00f3n de precios en el sitio web de AR, que son v\u00e1lidas para el per\u00edodo de viaje.<br \/>\nCancelaci\u00f3n<br \/>\nPuede cancelar en cualquier momento antes de la llegada. Importante es la recepci\u00f3n del aviso de cancelaci\u00f3n por parte de AR. En su propio inter\u00e9s, la cancelaci\u00f3n debe hacerse por escrito por correo electr\u00f3nico y solo se reconoce como tal, una vez que AR acusa recibo del correo electr\u00f3nico.<br \/>\nEn general, trataremos de alquilar la casa a otro hu\u00e9sped, si eso es posible, le reembolsaremos su pago inicial por completo o lo conservaremos para unas vacaciones futuras.<br \/>\nNuestro reclamo a tanto alzado por gastos de cancelaci\u00f3n para apartamentos y casas de vacaciones es:<br \/>\n&#8211; hasta 61 d\u00edas antes de la llegada 20% del precio del viaje<br \/>\n&#8211; de 60. a 35. d\u00eda antes de la llegada 50% del precio del viaje<br \/>\n&#8211; del 34 al 2. d\u00eda antes de la llegada 80% del precio del viaje<br \/>\n&#8211; Si se cancela m\u00e1s tarde, si no se presenta o si se interrumpe el viaje prematuramente, se cobrar\u00e1 \/ cobrar\u00e1 el precio total.<br \/>\nNo obstante las disposiciones mencionadas en el procedimiento de retiro, si ejerce su derecho, debe proporcionar un inquilino de reemplazo equivalente. Sin embargo, un requisito previo es que AR sea informado a su debido tiempo antes de la llegada con un aviso vinculante, para que se puedan tomar las nuevas disposiciones necesarias. El requisito es, adem\u00e1s, que el inquilino de reemplazo cumpla con las necesidades espec\u00edficas de los viajes y las regulaciones legales u \u00f3rdenes administrativas no lo impiden. Con la confirmaci\u00f3n del cambio de nombre por parte de AR, los nuevos inquilinos asumir\u00e1n los derechos y obligaciones del contrato de viaje.<br \/>\nLos pagos por adelantado no se reembolsan, sino que se liquidan entre el inquilino original y el inquilino de reemplazo sin la influencia de AR.<\/p>\n<h5><strong>Cancelaci\u00f3n por AR<\/strong><\/h5>\n<p>AR puede cancelar el contrato de viaje antes o despu\u00e9s del inicio del viaje:<br \/>\na) sin observar una fecha l\u00edmite si el viajero interrumpe permanentemente la ejecuci\u00f3n del viaje u otros viajeros a pesar de una advertencia o pone en peligro a otros por su comportamiento o se comporta de otra manera contraria al contrato.<br \/>\nb) sin observar una fecha l\u00edmite si la implementaci\u00f3n del viaje se hace significativamente m\u00e1s dif\u00edcil, en peligro o perjudicada como resultado de fuerza mayor o huelgas que no eran previsibles cuando se concluy\u00f3 el contrato.<br \/>\nSi AR cancela el contrato de viaje de acuerdo con el punto a), el precio del viaje se perder\u00e1. Si AR se retira del contrato de acuerdo con b), todas las cantidades pagadas ser\u00e1n reembolsadas inmediatamente; Se excluyen otros reclamos. Si AR cancela el contrato de acuerdo con b) despu\u00e9s del inicio del viaje, obtendr\u00e1 la parte del precio del viaje que corresponde a los gastos ahorrados de AR.<\/p>\n<h5><strong>Cambio de acuerdo<\/strong><\/h5>\n<p>Si el viaje no puede llevarse a cabo de conformidad con el contrato como resultado de una circunstancia que ocurri\u00f3 despu\u00e9s de la conclusi\u00f3n del contrato y de la cual el AR no es responsable, AR tiene derecho a cambiar los servicios de viaje, siempre que la desviaci\u00f3n del original reservado el servicio es objetivamente insignificante y razonable para el viajero, as\u00ed como el dise\u00f1o general del viaje.<\/p>\n<h5><strong>Responsabilidad<\/strong><\/h5>\n<p>AR es responsable de la diligencia debida de un hombre de negocios prudente<br \/>\na) la preparaci\u00f3n de viaje concienzuda<br \/>\nb) la prestaci\u00f3n adecuada de los servicios de viaje acordados en el contrato de viaje.<br \/>\nSe excluye la responsabilidad por fallas ocasionales o mal funcionamiento en el suministro de agua y \/ o energ\u00eda, as\u00ed como la responsabilidad por la disponibilidad operativa permanente de instalaciones como calefacci\u00f3n, piscinas, Wifi, etc. AR es responsable por da\u00f1os que no sean da\u00f1os corporales limitados a 1 veces el precio del viaje, en la medida en que el da\u00f1o al viajero no haya sido causado intencionalmente o por negligencia grave. Se excluyen otros reclamos por da\u00f1os y perjuicios contra AR.<\/p>\n<h5><strong>Obligaci\u00f3n de cooperar, garant\u00eda, exclusi\u00f3n de reclamos, plazo de prescripci\u00f3n.<\/strong><\/h5>\n<p>Dentro del marco de las disposiciones legales, usted est\u00e1 obligado a hacer todo lo razonable para ayudar a rectificar la interrupci\u00f3n y minimizar o prevenir cualquier da\u00f1o que pueda surgir. Esto se traduce en particular en la obligaci\u00f3n de informar las quejas de inmediato.<br \/>\nSi descubre alg\u00fan defecto, puede solicitar un remedio directamente de AR.<br \/>\nPuede presentar reclamos contra AR por escrito dentro de un mes. Por favor, por correo postal \/ registrado a la direcci\u00f3n anterior de AR. El requisito previo es que el servicio de viaje o el servicio de reemplazo que ha aceptado no se haya proporcionado de conformidad con el contrato, que haya notificado el defecto de inmediato y que no haya habido una reparaci\u00f3n adecuada. Si el viaje se ve significativamente afectado por defectos, puede cancelar el contrato de viaje. Sus reclamos contra AR caducan despu\u00e9s de un a\u00f1o. El per\u00edodo de limitaci\u00f3n comienza el d\u00eda en que el viaje debe finalizar de acuerdo con el contrato.<\/p>\n<h5><strong>Prohibici\u00f3n de asignaci\u00f3n<\/strong><\/h5>\n<p>Se excluye una cesi\u00f3n de reclamos contra terceros de AR to, incluidos c\u00f3nyuges y parientes. Asimismo, no se permite la afirmaci\u00f3n judicial de reclamos del participante del viaje por parte de terceros en su propio nombre.<\/p>\n<h5><strong>Seguro<\/strong><\/h5>\n<p>Le recomendamos que contrate un seguro de cancelaci\u00f3n de viaje al hacer la reserva. Nos complace organizar esto para usted: las primas del seguro pueden pagarse junto con el pago inicial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Condiciones de viaje Andalucia Rural (en lo sucesivo denominado AR) La Cueva (La Estrella &amp; El Sol), El Garzopo, La&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-15038","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9rminos y condiciones - Holiday homes in Andalusia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9rminos y condiciones - Holiday homes in Andalusia\" \/>\n<meta property=\"og:description\" content=\"Condiciones de viaje Andalucia Rural (en lo sucesivo denominado AR) La Cueva (La Estrella &amp; El Sol), El Garzopo, La...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Holiday homes in Andalusia\" \/>\n<meta property=\"article:modified_time\" content=\"2020-07-13T13:43:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/terminos-y-condiciones\\\/\",\"url\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/terminos-y-condiciones\\\/\",\"name\":\"T\u00e9rminos y condiciones - Holiday homes in Andalusia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/#website\"},\"datePublished\":\"2020-03-25T14:44:59+00:00\",\"dateModified\":\"2020-07-13T13:43:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/terminos-y-condiciones\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/terminos-y-condiciones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"T\u00e9rminos y condiciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.andaluciarural.eu\\\/\",\"name\":\"Holiday homes in Andalusia\",\"description\":\"Holiday homes in \u00d3rgiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.andaluciarural.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9rminos y condiciones - Holiday homes in Andalusia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/","og_locale":"es_ES","og_type":"article","og_title":"T\u00e9rminos y condiciones - Holiday homes in Andalusia","og_description":"Condiciones de viaje Andalucia Rural (en lo sucesivo denominado AR) La Cueva (La Estrella &amp; El Sol), El Garzopo, La...","og_url":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/","og_site_name":"Holiday homes in Andalusia","article_modified_time":"2020-07-13T13:43:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/","url":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/","name":"T\u00e9rminos y condiciones - Holiday homes in Andalusia","isPartOf":{"@id":"https:\/\/www.andaluciarural.eu\/#website"},"datePublished":"2020-03-25T14:44:59+00:00","dateModified":"2020-07-13T13:43:36+00:00","breadcrumb":{"@id":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.andaluciarural.eu\/es\/terminos-y-condiciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.andaluciarural.eu\/es\/"},{"@type":"ListItem","position":2,"name":"T\u00e9rminos y condiciones"}]},{"@type":"WebSite","@id":"https:\/\/www.andaluciarural.eu\/#website","url":"https:\/\/www.andaluciarural.eu\/","name":"Holiday homes in Andalusia","description":"Holiday homes in \u00d3rgiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.andaluciarural.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/comments?post=15038"}],"version-history":[{"count":3,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15038\/revisions"}],"predecessor-version":[{"id":16851,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15038\/revisions\/16851"}],"wp:attachment":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/media?parent=15038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}