{"id":15061,"date":"2020-03-26T19:47:22","date_gmt":"2020-03-26T18:47:22","guid":{"rendered":"https:\/\/www.andaluciarural.eu\/?page_id=15061"},"modified":"2020-03-26T19:47:22","modified_gmt":"2020-03-26T18:47:22","slug":"proteccion-de-datos","status":"publish","type":"page","link":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/","title":{"rendered":"Protecci\u00f3n de Datos"},"content":{"rendered":"<p>Utilizamos los datos proporcionados por usted para completar y procesar su pedido.<\/p>\n<p>Para todos los procesos de procesamiento de datos (por ejemplo, recopilaci\u00f3n, procesamiento y transmisi\u00f3n),<br \/>\nprocedemos de acuerdo con las regulaciones legales. Sus datos necesarios para las transacciones comerciales se<br \/>\nguardar\u00e1n y utilizar\u00e1n para el procesamiento de pedidos en la medida necesaria.<\/p>\n<p><strong>Cookies<\/strong><\/p>\n<p>Una \u00abcookie\u00bb es un peque\u00f1o archivo de datos que transferimos a su computadora cuando navega por nuestro sitio.<br \/>\nUna cookie solo puede contener informaci\u00f3n que enviamos a su computadora nosotros mismos; los datos privados<br \/>\nno se pueden leer con ella. Si acepta las cookies en nuestras p\u00e1ginas, no tenemos acceso a su informaci\u00f3n<br \/>\npersonal, pero podemos usar las cookies para identificar su computadora.<\/p>\n<p>Utilizamos cookies para los siguientes prop\u00f3sitos:<\/p>\n<p>\u2022 para que usted, p. Puede utilizar la personalizaci\u00f3n de nuestro sitio.<br \/>\n\u2022 para que podamos adaptar nuestro sitio a\u00fan mejor a las necesidades de nuestros clientes.<\/p>\n<p>Utilizamos cookies \u00abpermanentes\u00bb: permanecen en su computadora para simplificar los servicios de compras,<br \/>\npersonalizaci\u00f3n y registro en sus pr\u00f3ximas visitas. Adem\u00e1s, solo tiene que ingresar su contrase\u00f1a una vez en los<br \/>\nsitios web que requieren registro. El usuario puede eliminar manualmente las cookies \u00abpermanentes\u00bb.<\/p>\n<p>La mayor\u00eda de los navegadores aceptan cookies por defecto. Puede permitir o no permitir cookies temporales y<br \/>\nguardadas independientemente una de la otra en la configuraci\u00f3n de seguridad. Si desactiva las cookies, es<br \/>\nposible que algunas funciones de nuestro sitio web no est\u00e9n disponibles para usted y que algunos sitios web no se<br \/>\nmuestren correctamente.<\/p>\n<p><strong>Complementos de Facebook (plug-ins)<\/strong><\/p>\n<p>Nuestro sitio web tambi\u00e9n contiene programas (complementos o plug-ins) de la red social Facebook. Estos son<br \/>\noperados exclusivamente por Facebook Inc., 1601 S. California Ave, Palo Alto, CA 94304, EE. UU. (Facebook).<br \/>\nLos complementos se identifican en nuestro sitio web mediante el logotipo de Facebook o la adici\u00f3n \u00abMe gusta\u00bb.<br \/>\nCuando visita un sitio web en nuestro sitio web que contiene dicho complemento, su navegador establece una<br \/>\nconexi\u00f3n directa con los servidores de Facebook, que a su vez transmite el contenido del complemento a su<br \/>\nnavegador y lo integra en el sitio web que se muestra. Esto reenviar\u00e1 la informaci\u00f3n de que ha visitado nuestro<br \/>\nsitio web a Facebook. Si ha iniciado sesi\u00f3n en Facebook a trav\u00e9s de su cuenta de usuario personal mientras visita<br \/>\nnuestro sitio web, Facebook puede asignar la visita del sitio web a esta cuenta. Al interactuar con complementos,<br \/>\np. Al hacer clic en el bot\u00f3n \u00abMe gusta\u00bb o dejar un comentario, esta informaci\u00f3n correspondiente se transmite<br \/>\ndirectamente a Facebook y se almacena all\u00ed. Si desea evitar dicha transmisi\u00f3n de datos, debe cerrar sesi\u00f3n en su<br \/>\ncuenta de Facebook antes de visitar nuestro sitio web.<\/p>\n<p>Para el prop\u00f3sito y el alcance de la recopilaci\u00f3n de datos por parte de Facebook y el posterior procesamiento y<br \/>\nuso de sus datos all\u00ed, as\u00ed como sus derechos y opciones de configuraci\u00f3n para proteger su privacidad, consulte la<br \/>\ninformaci\u00f3n de protecci\u00f3n de datos de Facebook (http: \/\/ de-de. facebook.com\/privacy\/explanation .php).<\/p>\n<p><strong>Informaci\u00f3n sobre las cookies de Google Analytics<\/strong><\/p>\n<p>Este sitio web utiliza Google Analytics, un servicio de an\u00e1lisis web proporcionado por Google Inc. (\u00abGoogle\u00bb).<br \/>\nGoogle Analytics utiliza las llamadas \u00abcookies\u00bb, archivos de texto que se guardan en su computadora y que<br \/>\npermiten un an\u00e1lisis de su uso del sitio web. La informaci\u00f3n generada por la cookie sobre su uso de este sitio web<br \/>\n(incluida su direcci\u00f3n IP) se transmite a un servidor de Google en los EE. UU. Y se almacena all\u00ed. Google utilizar\u00e1<br \/>\nesta informaci\u00f3n para evaluar su uso del sitio web, para compilar informes sobre la actividad del sitio web para los<br \/>\noperadores del sitio web y para proporcionar otros servicios relacionados con la actividad del sitio web y el uso de<br \/>\nInternet. Google tambi\u00e9n puede transferir esta informaci\u00f3n a terceros si as\u00ed lo exige la ley o si terceros procesan<br \/>\nestos datos en nombre de Google. En ning\u00fan caso Google vincular\u00e1 su direcci\u00f3n IP con otros datos de Google.<br \/>\nPuede evitar la instalaci\u00f3n de cookies configurando el software de su navegador en consecuencia; sin embargo,<br \/>\nnos gustar\u00eda se\u00f1alar que, en este caso, es posible que no pueda utilizar todas las funciones de este sitio web en<br \/>\ntoda su extensi\u00f3n. Al utilizar este sitio web, usted acepta el procesamiento de datos sobre usted por parte de<br \/>\nGoogle de la manera y para los fines establecidos anteriormente.<\/p>\n<p>Persona de contacto para protecci\u00f3n de datos:<br \/>\nSi tiene alguna pregunta sobre la recopilaci\u00f3n, el procesamiento o el uso de sus datos personales, informaci\u00f3n,<br \/>\ncorrecci\u00f3n, bloqueo o eliminaci\u00f3n de datos o renovaci\u00f3n del consentimiento, comun\u00edquese con:<\/p>\n<p>Oficial de protecci\u00f3n de datos: Stefan Told<\/p>\n<p><a href=\"mailto:info@andaluciarural.eu\">info@andaluciarural.eu<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Utilizamos los datos proporcionados por usted para completar y procesar su pedido. Para todos los procesos de procesamiento de datos&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"footnotes":""},"class_list":["post-15061","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Protecci\u00f3n de Datos - Holiday homes in Andalusia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Protecci\u00f3n de Datos - Holiday homes in Andalusia\" \/>\n<meta property=\"og:description\" content=\"Utilizamos los datos proporcionados por usted para completar y procesar su pedido. Para todos los procesos de procesamiento de datos...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/\" \/>\n<meta property=\"og:site_name\" content=\"Holiday homes in Andalusia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/proteccion-de-datos\\\/\",\"url\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/proteccion-de-datos\\\/\",\"name\":\"Protecci\u00f3n de Datos - Holiday homes in Andalusia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/#website\"},\"datePublished\":\"2020-03-26T18:47:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/proteccion-de-datos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/proteccion-de-datos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/proteccion-de-datos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.andaluciarural.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Protecci\u00f3n de Datos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.andaluciarural.eu\\\/#website\",\"url\":\"https:\\\/\\\/www.andaluciarural.eu\\\/\",\"name\":\"Holiday homes in Andalusia\",\"description\":\"Holiday homes in \u00d3rgiva\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.andaluciarural.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Protecci\u00f3n de Datos - Holiday homes in Andalusia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/","og_locale":"es_ES","og_type":"article","og_title":"Protecci\u00f3n de Datos - Holiday homes in Andalusia","og_description":"Utilizamos los datos proporcionados por usted para completar y procesar su pedido. Para todos los procesos de procesamiento de datos...","og_url":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/","og_site_name":"Holiday homes in Andalusia","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/","url":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/","name":"Protecci\u00f3n de Datos - Holiday homes in Andalusia","isPartOf":{"@id":"https:\/\/www.andaluciarural.eu\/#website"},"datePublished":"2020-03-26T18:47:22+00:00","breadcrumb":{"@id":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.andaluciarural.eu\/es\/proteccion-de-datos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.andaluciarural.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Protecci\u00f3n de Datos"}]},{"@type":"WebSite","@id":"https:\/\/www.andaluciarural.eu\/#website","url":"https:\/\/www.andaluciarural.eu\/","name":"Holiday homes in Andalusia","description":"Holiday homes in \u00d3rgiva","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.andaluciarural.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/comments?post=15061"}],"version-history":[{"count":1,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15061\/revisions"}],"predecessor-version":[{"id":15062,"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/pages\/15061\/revisions\/15062"}],"wp:attachment":[{"href":"https:\/\/www.andaluciarural.eu\/es\/wp-json\/wp\/v2\/media?parent=15061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}